{"id":160,"date":"2024-12-30T12:28:01","date_gmt":"2024-12-30T11:28:01","guid":{"rendered":"https:\/\/mvtfdesign.com\/?post_type=product&#038;p=160"},"modified":"2026-07-25T08:00:57","modified_gmt":"2026-07-25T06:00:57","slug":"carte-de-visite-recto-verso","status":"publish","type":"product","link":"https:\/\/mvtfdesign.com\/index.php\/produit\/carte-de-visite-recto-verso\/","title":{"rendered":"Carte de visite Recto-Verso"},"content":{"rendered":"<p>Pour booster votre communication commerciale et vous fournir une papeterie de qualit\u00e9, MVTF Design vous propose un large choix de cartes de visite avec une multitude de supports et de finitions disponible en impression en ligne. L&rsquo;impression de cartes enrichie votre communication visuelle et MVTF Design vous simplifie la conception : imprimer vos cartes de visite en ligne. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour booster votre communication commerciale et vous fournir une papeterie de qualit\u00e9, MVTF Design vous propose un large choix de cartes de visite<\/p>\n","protected":false},"featured_media":159,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":["post-160","product","type-product","status-publish","has-post-thumbnail","product_cat-carte-de-visite","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/product\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/comments?post=160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/media\/159"}],"wp:attachment":[{"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=160"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=160"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mvtfdesign.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}